{"id":248,"count":0,"description":"","link":"https:\/\/levelup-br-tim.upp.st\/pt-br\/course-category\/technology-br\/","name":"Tecnologia","slug":"technology-br","taxonomy":"course_category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/levelup-br-tim.upp.st\/pt-br\/wp-json\/wp\/v2\/course_category\/248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/levelup-br-tim.upp.st\/pt-br\/wp-json\/wp\/v2\/course_category"}],"about":[{"href":"https:\/\/levelup-br-tim.upp.st\/pt-br\/wp-json\/wp\/v2\/taxonomies\/course_category"}],"wp:post_type":[{"href":"https:\/\/levelup-br-tim.upp.st\/pt-br\/wp-json\/wp\/v2\/lp_course?course_category=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}